{"id":310375,"date":"2026-07-20T15:14:53","date_gmt":"2026-07-20T15:14:53","guid":{"rendered":"https:\/\/academy.gestioo.com\/taller\/?post_type=docs&#038;p=310375"},"modified":"2026-07-20T16:31:14","modified_gmt":"2026-07-20T16:31:14","password":"","slug":"configuracion-de-preventivos","status":"publish","type":"docs","link":"https:\/\/academy.gestioo.com\/taller\/docs\/configuracion-de-preventivos\/","title":{"rendered":"Configuraci\u00f3n de Preventivos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En esta gu\u00eda, te proporcionaremos instrucciones detalladas para configurar los turnos \/ preventivos dentro del sistema <b>Gestioo<sub><small style=\"font-size:10px;\">\u00ae<\/small><\/sub><\/b>. Esta funcionalidad permite definir las notificaciones de vencimiento, configurar la duraci\u00f3n predeterminada de los turnos, establecer l\u00edmites de solapamiento, determinar l\u00edmites diarios por t\u00e9cnico o generales y asignar el \u00e1rea y el estado inicial de cada sucursal, optimizando la organizaci\u00f3n y el seguimiento de los servicios programados.<\/p>\n\n\n<p>Confiamos en que este manual te ayudar\u00e1 a aprovechar al m\u00e1ximo el <b>Software<\/b> <i class=\"fa-solid fa-rocket-launch\"><\/i><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Acceso a configuraci\u00f3n de turnos \/ preventivos<\/h2>\n\n\n\n<ol class=\"wp-block-list oc-pasos\">\n<li>Ingresa al men\u00fa lateral.<\/li>\n\n\n\n<li>Realiza <span class=\"g_clic\"><i class=\"fa-solid fa-arrow-pointer\"><\/i> clic<\/span> en \u00ab<strong>Configuraci\u00f3n de taller<\/strong>\u00ab.<\/li>\n\n\n\n<li>Luego realiza <span class=\"g_clic\"><i class=\"fa-solid fa-arrow-pointer\"><\/i> clic<\/span> en \u00ab<strong>Configuraci\u00f3n<\/strong>\u00ab.<\/li>\n\n\n\n<li>Ingresa a la pesta\u00f1a \u00ab<strong>Preventivos<\/strong>\u00ab.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Podr\u00e1s visualizar la secci\u00f3n de configuraci\u00f3n de turnos \/ preventivos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Configuraci\u00f3n de turnos \/ preventivos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro de esta secci\u00f3n encontrar\u00e1s los siguientes campos:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"864\" src=\"https:\/\/academy.gestioo.com\/taller\/wp-content\/uploads\/2026\/07\/image-87.png\" alt=\"\" class=\"wp-image-310378\" srcset=\"https:\/\/academy.gestioo.com\/taller\/wp-content\/uploads\/2026\/07\/image-87.png 1152w, https:\/\/academy.gestioo.com\/taller\/wp-content\/uploads\/2026\/07\/image-87-980x735.png 980w, https:\/\/academy.gestioo.com\/taller\/wp-content\/uploads\/2026\/07\/image-87-480x360.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1152px, 100vw\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"manual_orden_alfabetico\">A<\/span> <strong>Notificaciones de preventivos:<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Correo (Env\u00edo reporte general)<\/strong>: Permite definir el correo destinado al env\u00edo del reporte general.<\/li>\n\n\n\n<li><strong>Notificar a cliente<\/strong>: Permite indicar si el cliente ser\u00e1 notificado sobre el preventivo.<\/li>\n\n\n\n<li><strong>Notificar vencimiento<\/strong>: Permite definir con cu\u00e1ntos d\u00edas de anticipaci\u00f3n se notificar\u00e1 el vencimiento.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"manual_orden_alfabetico\">B<\/span> <strong>Turnos:<\/strong> Permite configurar la duraci\u00f3n predeterminada de los turnos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"manual_orden_alfabetico\">C<\/span> <strong>M\u00e1ximo solapamiento:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Por t\u00e9cnico<\/strong>: Permite definir la cantidad m\u00e1xima de turnos que pueden superponerse para un mismo t\u00e9cnico.<\/li>\n\n\n\n<li><strong>General<\/strong>: Permite definir la cantidad m\u00e1xima de turnos que pueden superponerse entre todos los t\u00e9cnicos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"manual_orden_alfabetico\">D<\/span> <strong>L\u00edmite diario:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Por t\u00e9cnico<\/strong>: Permite establecer un l\u00edmite diario de turnos preventivos por t\u00e9cnico.<\/li>\n\n\n\n<li><strong>General<\/strong>: Permite establecer un l\u00edmite diario general de turnos preventivos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"manual_orden_alfabetico\">E<\/span> <strong>Sucursales:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bot\u00f3n \u00ab<strong>Crear<\/strong>\u00ab: Permite agregar una nueva configuraci\u00f3n de \u00e1rea y estado inicial para los preventivos registrados.<\/li>\n\n\n\n<li><strong>Listado de sucursales<\/strong>: Muestra la sucursal, el \u00e1rea y el estado configurado.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">[guardar]<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Configurar sucursal para preventivos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Al seleccionar el <strong>bot\u00f3n \u00abCrear\u00bb<\/strong> dentro de la secci\u00f3n <strong>\u00abSucursales\u00bb<\/strong>, se abre el modal <strong>\u00abEditar Sucursal\u00bb<\/strong>, donde se puede configurar la sucursal, el \u00e1rea y el estado predeterminado que se asignar\u00e1n a las \u00f3rdenes de trabajo correspondientes a preventivos registrados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"235\" src=\"https:\/\/academy.gestioo.com\/taller\/wp-content\/uploads\/2026\/07\/image-88.png\" alt=\"\" class=\"wp-image-310379\" srcset=\"https:\/\/academy.gestioo.com\/taller\/wp-content\/uploads\/2026\/07\/image-88.png 984w, https:\/\/academy.gestioo.com\/taller\/wp-content\/uploads\/2026\/07\/image-88-980x234.png 980w, https:\/\/academy.gestioo.com\/taller\/wp-content\/uploads\/2026\/07\/image-88-480x115.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 984px, 100vw\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sucursal<\/strong>: Permite seleccionar la sucursal a la que se aplicar\u00e1 la configuraci\u00f3n.<\/li>\n\n\n\n<li><strong>\u00c1rea<\/strong>: Permite definir el \u00e1rea inicial de las \u00f3rdenes de trabajo generadas desde los preventivos.<\/li>\n\n\n\n<li><strong>Estado<\/strong>: Permite seleccionar el estado inicial de las \u00f3rdenes de trabajo generadas desde los preventivos.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusi\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La configuraci\u00f3n de turnos \/ preventivos en <b>Gestioo<sub><small style=\"font-size:10px;\">\u00ae<\/small><\/sub><\/b> permite definir las notificaciones, la duraci\u00f3n de los turnos, los l\u00edmites de solapamiento y la cantidad diaria de registros. Adem\u00e1s, facilita la asignaci\u00f3n del \u00e1rea y el estado inicial de las \u00f3rdenes de trabajo generadas desde preventivos, mejorando la planificaci\u00f3n y el seguimiento de los servicios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta gu\u00eda, te proporcionaremos instrucciones detalladas para configurar los turnos \/ preventivos dentro del sistema Gestioo\u00ae. Esta funcionalidad permite definir las notificaciones de vencimiento, configurar la duraci\u00f3n predeterminada de los turnos, establecer l\u00edmites de solapamiento, determinar l\u00edmites diarios por t\u00e9cnico o generales y asignar el \u00e1rea y el estado inicial de cada sucursal, optimizando [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"doc_category":[90],"doc_tag":[],"class_list":["post-310375","docs","type-docs","status-publish","hentry","doc_category-configuracion-taller"],"year_month":"2026-09","word_count":441,"total_views":"41","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Gaston Bravo","author_nicename":"gaston","author_url":"https:\/\/academy.gestioo.com\/taller\/author\/gaston\/"},"doc_category_info":[{"term_name":"Configuraci\u00f3n (Taller)","term_url":"https:\/\/academy.gestioo.com\/taller\/docs-category\/configuracion-taller\/"}],"doc_tag_info":[],"knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/academy.gestioo.com\/taller\/wp-json\/wp\/v2\/docs\/310375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/academy.gestioo.com\/taller\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/academy.gestioo.com\/taller\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/academy.gestioo.com\/taller\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/academy.gestioo.com\/taller\/wp-json\/wp\/v2\/comments?post=310375"}],"version-history":[{"count":4,"href":"https:\/\/academy.gestioo.com\/taller\/wp-json\/wp\/v2\/docs\/310375\/revisions"}],"predecessor-version":[{"id":310654,"href":"https:\/\/academy.gestioo.com\/taller\/wp-json\/wp\/v2\/docs\/310375\/revisions\/310654"}],"wp:attachment":[{"href":"https:\/\/academy.gestioo.com\/taller\/wp-json\/wp\/v2\/media?parent=310375"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/academy.gestioo.com\/taller\/wp-json\/wp\/v2\/doc_category?post=310375"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/academy.gestioo.com\/taller\/wp-json\/wp\/v2\/doc_tag?post=310375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}